{"id":29387,"date":"2025-07-05T11:32:44","date_gmt":"2025-07-05T09:32:44","guid":{"rendered":"https:\/\/esclaustre.com\/event\/julia-beatloop-3\/"},"modified":"2025-09-02T09:20:17","modified_gmt":"2025-09-02T07:20:17","slug":"julia-beatloop-3","status":"publish","type":"tribe_events","link":"https:\/\/esclaustre.com\/en\/event\/julia-beatloop-3\/","title":{"rendered":"J\u00falia Beatloop"},"content":{"rendered":"<h2><strong>\u00abJ\u00falia Beatloop\u00bb s&#8217;enfila de nou a l&#8217;escenari d&#8217;Es Claustre<\/strong><\/h2>\n<p><strong>J\u00falia Beatloop<\/strong> \u00e9s una artista solista i autodidacta que presenta les seves composicions musicals amb una fusi\u00f3 d&#8217;estils i amb tocs rap, reggae, electr\u00f2nica i poesia en un format original i en\u00e8rgic.<\/p>\n<p>Tota sola acompanyada de la seva loopstation i una varietat d&#8217;instruments (piano, guitarra, mel\u00f2dica, harm\u00f2nica&#8230;) crea els seus temes en viu, capa per capa, combinant el ritme, palaura per paraula i emoci\u00f3.<\/p>\n<p>Un concert que entrega m\u00e9s que m\u00fasica, un viatge musical on poder connectar amb les lletres que composa, el so, la profunditat de sa vida i transformant un espai per poder desconnectar de la cotidianitat i connectar-se amb si mateix.<\/p>\n<p>Vine a descobrir la creativitat de l&#8217;illa de la m\u00e0 de na J\u00falia Beatloop!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acompanyada del seu piano, de la guitarra, la mel\u00f2dica, l\u2019harm\u00f2nica i la seva inseparable loopstation, la J\u00falia Beatloop ens apropa un directe amb bases per generar un show que va m\u00e9s enll\u00e0 d\u2019un simple repertori musical. A la J\u00falia li agrada sentir l\u2019espai all\u00e0 on toca, notar la gent i la proximitat amb el p\u00fablic que l\u2019escolta, una condici\u00f3 que \u00e9s vital per aquesta jove artista menorquina.<\/p>\n","protected":false},"author":1,"featured_media":29381,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[4496,210],"tribe_events_cat":[1423,4150],"class_list":["post-29387","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-julia-beatloop-en","tag-menorca-en","tribe_events_cat-agenda-menorca-en","tribe_events_cat-altres-esdeveniments-en","cat_agenda-menorca-en","cat_altres-esdeveniments-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events\/29387","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events\/29387\/revisions"}],"predecessor-version":[{"id":29585,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events\/29387\/revisions\/29585"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/media\/29381"}],"wp:attachment":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/media?parent=29387"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tags?post=29387"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=29387"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}