{"id":32535,"date":"2026-09-01T10:30:03","date_gmt":"2026-09-01T08:30:03","guid":{"rendered":"https:\/\/esclaustre.com\/event\/la-boca-erotica-sessio-oficial-2-concert\/"},"modified":"2026-09-01T10:43:35","modified_gmt":"2026-09-01T08:43:35","slug":"la-boca-erotica-sessio-oficial-2-concert","status":"publish","type":"tribe_events","link":"https:\/\/esclaustre.com\/en\/event\/la-boca-erotica-sessio-oficial-2-concert\/","title":{"rendered":"La Boca Er\u00f3tica: Secci\u00f3 Oficial 2 + Concert Chico Oca\u00f1a"},"content":{"rendered":"<h2><strong>\u00abLa Boca Er\u00f3tica\u00bb IX Festival Internacional de Cinema de Tem\u00e0tica Sexual<\/strong><\/h2>\n<p>Tres dies de projeccions i activitats al voltant de la tem\u00e0tica er\u00f2tica en un festival que tindr\u00e0 3 dies seguits d&#8217;activitat <a href=\"https:\/\/esclaustre.com\/en\/\">Es Claustre<\/a>.<\/p>\n<p>Divendres 25: <strong><span class=\"\">Sessi\u00f3 Oficial 2<\/span><\/strong><\/p>\n<p>Sel\u00b7lecci\u00f3 Oficial de curtmetratges internacionals amb la col\u00b7laboraci\u00f3 del <a href=\"https:\/\/www.mecalbcn.org\/\" target=\"_blank\" rel=\"noopener\">MECAL<\/a> short Film Festival de Barcelona i el <a href=\"https:\/\/giff.mx\/\" target=\"_blank\" rel=\"noopener\">Guanajuato Film Festival<\/a> de M\u00e9xico.<\/p>\n<p><b class=\"\"><span class=\"\">Presenta: <\/span><\/b><span class=\"\">Javier Mu\u00f1iz<\/span><\/p>\n<p style=\"font-weight: 400;\"><strong>Performance:<\/strong> Companyia <strong>La Perrerie<\/strong><\/p>\n<p class=\"wp-block-paragraph\"><strong>La Perrerie <\/strong>\u00e9s una companyia de teatre experimental feminista amb base a Menorca. Fundada per <strong>\u00c1ngela Tortajada<\/strong>, <strong>La Perrerie<\/strong> \u00e9s tamb\u00e9 un laboratori esc\u00e8nic que busca expandir els l\u00edmits de la contemporane\u00eftat, jugant amb f\u00f3rmules dissidents a les convencionals i deixant projectes oberts per tancar-los en temps real amb els cossos davant del p\u00fablic. Les seves obres de creaci\u00f3 pr\u00f2pia tenen una tend\u00e8ncia a l\u2019autoficci\u00f3 i a les noves dramat\u00fargies, integrant el treball del cos i la fisicalitat. Les seves propostes sorgeixen del desig de connectar de manera profunda i personal amb el p\u00fablic, fet que tamb\u00e9 pot acostar el seu treball a la performance.<\/p>\n<p style=\"font-weight: 400;\"><strong>Concert Clausura: Chico Oca\u00f1a<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Chicco Oca\u00f1a<\/strong>, veu<\/p>\n<p style=\"font-weight: 400;\"><strong>Cristian \u201cEl Chupete<\/strong>, guitarra<\/p>\n<p style=\"font-weight: 400;\">Chicco Oca\u00f1a, creador del \u201cFlamenco Biily\u201d.\u00a0 Fundador, vocalista y compositor de todas las letras canallas de <strong>M\u00e1rtires del Comp\u00e1s<\/strong>. Actualmente cantante en solitario y siempre poeta. En 2024 publica su libro \u201cLetras pa da el cante\u201d con la editorial Fuego Fatuo y publicar\u00e1 en breve su segundo libro. Viene acompa\u00f1ado a la guitarra por Cristian \u201cEl Chupete\u201d de origen Dan\u00e9s y residente en Jerez desde hace 15 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Boca Er\u00f3tica: 23, 24 i 25 de setembre Es Claustre. Sessi\u00f3 Oficial 2 + Concert Chico Oca\u00f1a.<\/p>\n","protected":false},"author":1,"featured_media":32511,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[4794,4788],"tribe_events_cat":[1423,4150],"class_list":["post-32535","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-chico-ocana","tag-la-boca-erotica","tribe_events_cat-agenda-menorca-en","tribe_events_cat-altres-esdeveniments-en","cat_agenda-menorca-en","cat_altres-esdeveniments-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events\/32535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":3,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events\/32535\/revisions"}],"predecessor-version":[{"id":32544,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events\/32535\/revisions\/32544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/media\/32511"}],"wp:attachment":[{"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/media?parent=32535"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tags?post=32535"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/esclaustre.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=32535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}